{"id":14153,"date":"2023-03-20T10:57:00","date_gmt":"2023-03-20T10:57:00","guid":{"rendered":"https:\/\/stage-bgaming-players-hub.pantheonsite.io\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming\/"},"modified":"2026-02-16T13:25:09","modified_gmt":"2026-02-16T13:25:09","slug":"crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming","status":"publish","type":"news","link":"https:\/\/bgaming.com\/es\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming","title":{"rendered":"DESVELA EL MISTERIO DE LOS HUEVOS PERDIDOS EN LA TRAGAMONEDAS EASTER HEIST"},"content":{"rendered":"\n<div style=\"min-height:100px\" class=\"article-head container align wp-block-acf-article-head has-background is-layout-flow wp-block-acf-article-head-is-layout-flow\" id=\"acf-block-6807ac00ef388\">\n\n    <div class=\"acf-innerblocks-container article-head-wrapper\">\n\n<p class=\"article-breadcrumbs wp-block-paragraph\"><a href=\"https:\/\/bgaming.com\/es\/news\">todas las noticias<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large article-featured\"><img decoding=\"async\" src=\"https:\/\/bgaming.com\/wp-content\/uploads\/2025\/05\/64fa3548c8bc1791250593c1_641c36d5c8ba402ac8f76732_Easter_Heist_News_Page_Hero.webp\" alt=\"\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\" style=\"padding-bottom:1rem\">\n<div class=\"article-types align wp-block-acf-article-types has-background is-layout-flow wp-block-acf-article-types-is-layout-flow\" id=\"acf-block-68210475430f1\">\n\n\n            <div class=\"article-type\">\n        Lanzamiento del Juego      <\/div>\n      <\/div>\n\n\n<div class=\"wp-block-post-date\">February 16, 2026<\/div><\/div>\n\n<\/div>\n\n                <div class=\"hidden article-featured-mobile image-js-true\" data-scr=\"https:\/\/bgaming.com\/wp-content\/uploads\/2025\/05\/64fa353b8e135879f5725e17_641c36ca339b17a540336293_Easter_Heist_All-News.webp\"\n                 data-alt=\"\"><\/div>\n            \n<\/div>\n\n\n<div style=\"min-height:100px\" class=\"article-content container show-table-of-contents align wp-block-acf-article-content has-background is-layout-flow wp-block-acf-article-content-is-layout-flow\" id=\"acf-block-6807ac81aac20\">\n            <div class=\"article-navigation navigation navigation-custom\">\n            <div class=\"navigation-title navigation-title-custom\">\n                Table Of Contents                <span>\n                    <svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='1rem' height='1rem' viewBox='0 0 16 16' fill='000000'>\n                        <path fill-rule='evenodd' clip-rule='evenodd' d='M8.00136 10.6663C8.15336 10.6663 8.3047 10.615 8.42803 10.5117L12.428 7.17833C12.7107 6.943 12.7494 6.52233 12.5134 6.23966C12.278 5.957 11.858 5.919 11.5747 6.15433L7.99403 9.13833L4.41936 6.26166C4.1327 6.031 3.7127 6.07633 3.48203 6.363C3.25136 6.64966 3.2967 7.069 3.58336 7.30033L7.58336 10.519C7.70536 10.617 7.85336 10.6663 8.00136 10.6663'><\/path>\n                    <\/svg>\n                <\/span>\n            <\/div>\n            <div class=\"navigation-items navigation-list\"><\/div>\n        <\/div>\n    \n  <div class=\"article-left\">\n    <div class=\"acf-innerblocks-container article-content-wrapper \">\n<h1 class=\"wp-block-post-title\">DESVELA EL MISTERIO DE LOS HUEVOS PERDIDOS EN LA TRAGAMONEDAS EASTER HEIST<\/h1>\n\n\n<p class=\"wp-block-paragraph\">\u200d<strong>Ven y ay\u00fadanos <\/strong><a href=\"https:\/\/bgaming.com\/es\/games\/slot-machine-2\"><strong>Tragaperras Gaming<\/strong><\/a><strong> proveedor resolver\u00e1 el misterio de los huevos que faltan en la \u00faltima versi\u00f3n de marzo, <\/strong><a href=\"https:\/\/bgaming.com\/es\/games\/easter-heist\" target=\"_blank\"><strong>Asalto de Pascua<\/strong><\/a><strong>, llena del delicioso resplandor del sol y las vibraciones primaverales.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El astuto conejo de Pascua, uno de los personajes principales de la nueva tragaperras online de 5&#215;3 con 25 l\u00edneas de pago, se ha llevado todos los huevos dorados relucientes. Los jugadores deber\u00e1n correr tras \u00e9l a toda velocidad a trav\u00e9s de una serie de impresionantes funciones, recogiendo tantos huevos ca\u00eddos con multiplicadores explosivos como sea posible, con la posibilidad de conseguir una ganancia m\u00e1xima de hasta 5624 veces. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Easter Heist est\u00e1 repleto de una volatilidad alt\u00edsima y un RTP del 96,08%, lo que promete lujosos juegos de bonificaci\u00f3n para mantener la emoci\u00f3n el mayor tiempo posible. Si caen m\u00e1s de 3 s\u00edmbolos dispersos, se activan las tiradas gratis con los s\u00edmbolos que m\u00e1s pagan y la funci\u00f3n de reactivaci\u00f3n, que acerca a los jugadores a atrapar al ladr\u00f3n de conejos. Pero la parte m\u00e1s emocionante comienza con m\u00e1s de 6 huevos dorados en los carretes, y se inicia la funci\u00f3n Coin Respin con los s\u00edmbolos \u00abPlus Spin\u00bb y \u00abCollect Egg\u00bb que aparecen al azar para llevarse el Mega Jackpot. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo tienes tiempo para buscar al Conejo de Pascua? No importa, ya que los jugadores pueden aprovechar la funci\u00f3n de compra de bonos integrada y comenzar la ronda de tiradas gratis o Coin Respin sin demora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNuestro talentoso equipo ha creado un juego con tem\u00e1tica de Pascua que a\u00f1ade una diversidad perfecta a la selecci\u00f3n de tragamonedas navide\u00f1as de los casinos\u00bb, coment\u00f3 Yulia Aliakseyeva, codirectora de operaciones de BGaming. \u00abCon el carism\u00e1tico conejo de Pascua como protagonista y la cautivadora funci\u00f3n Coin Respin, mejorada con un bote impresionante, seguro que los jugadores seguir\u00e1n enganchados\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rel\u00e1jese y sum\u00e9rjase en el ambiente de las vacaciones de primavera con la colecci\u00f3n de t\u00edtulos y redise\u00f1os de Pascua de BGaming Games <a href=\"https:\/\/bgaming.com\/es\/games\/easter-heist\" target=\"_blank\">Asalto de Pascua<\/a>, <a href=\"https:\/\/bgaming.com\/es\/games\/easter-plinko\" target=\"_blank\">Plinko de Pascua<\/a>, Hola Pascua, <a href=\"https:\/\/bgaming.com\/es\/games\/lucky-farm-bonanza-easter\" target=\"_blank\">Bonanza de Lucky Farm<\/a> (resinando), <a href=\"https:\/\/bgaming.com\/es\/games\/fruit-million-easter\" target=\"_blank\">Mill\u00f3n de frutas<\/a> (resina).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200d<\/p>\n\n<\/div>\n  <\/div>\n  <div class=\"article-right\">\n    <div class=\"component_subscribe-article\">\n\t                <div class=\"article-navigation navigation\">\n                <div class=\"mobile-quick-list\">\n                    Table Of Contents                    <span class=\"closed-nav\">\n                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M3.33398 3.33398L12.6667 12.6667\" stroke=\"#292D32\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <path d=\"M3.33331 12.6667L12.666 3.33398\" stroke=\"#292D32\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"navigation-title\">Tabla de Contenidos<\/div>\n                <div class=\"navigation-items navigation-list\"><\/div>\n            <\/div>\n\t    \n        \n      <div class=\"wrap_social-article\">\n        <div class=\"w-embed\">\n          <a href=\"https:\/\/bgaming.com\/es\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming\" class=\"icon_wrap-social sub copy\">\n            <div class=\"icon-1x1-small sub\"><svg class=\"icon-black\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1.25rem\" height=\"1.25rem\" viewBox=\"0 0 20 20\" fill=\"#17161C\">\n                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M9.60496 3.24912C11.4233 1.42662 14.3575 1.09746 16.3841 2.68246C18.8116 4.58079 18.9708 8.11829 16.8616 10.2325L15.6758 11.42C15.3483 11.7483 14.8183 11.7483 14.4908 11.42C14.1633 11.0925 14.1633 10.56 14.4908 10.2325L15.6758 9.04412C17.055 7.66329 16.98 5.36746 15.4491 4.08579C14.0933 2.94996 12.0583 3.16662 10.8091 4.41829L9.74829 5.48079C9.42163 5.80912 8.88996 5.80912 8.56329 5.48079C8.23579 5.15329 8.23246 4.62412 8.71079 4.14496L9.60496 3.24912ZM11.0765 7.74354L7.74321 11.0769C7.41738 11.4027 7.41738 11.9294 7.74321 12.2552C7.90571 12.4177 8.11904 12.4994 8.33238 12.4994C8.54571 12.4994 8.75905 12.4177 8.92155 12.2552L12.2549 8.92187C12.5807 8.59604 12.5807 8.06937 12.2549 7.74354C11.929 7.41771 11.4024 7.41771 11.0765 7.74354ZM10.2326 14.4965L9.17096 15.5556C7.92013 16.8031 5.88096 17.0181 4.52429 15.8873C2.99179 14.6106 2.91596 12.3223 4.29679 10.9448L5.48429 9.76146C5.81179 9.43479 5.81179 8.90479 5.48429 8.57729C5.15679 8.25146 4.62513 8.25146 4.29679 8.57729L3.23429 9.63812C1.42429 11.4431 1.10679 14.3465 2.67179 16.3665C4.56429 18.8106 8.11429 18.9756 10.2326 16.864L11.4201 15.6806C11.7476 15.3531 11.7476 14.824 11.4201 14.4965C11.0918 14.169 10.561 14.169 10.2326 14.4965Z\"><\/path>\n              <\/svg><\/div>\n          <\/a>\n        <\/div>\n        <div class=\"w-embed\">\n          <a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&amp;url=https:\/\/bgaming.com\/es\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming\" class=\"icon_wrap-social sub\">\n            <div class=\"icon-1x1-small w-embed\"><svg class=\"icon-black\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1.25rem\" height=\"1.25rem\" viewBox=\"0 0 20 20\" fill=\"#17161C\">\n                <g clip-path=\"url(#clip0_1106_86860)\">\n                  <path d=\"M19.9951 20.0008V20H20.0001V12.665C20.0001 9.07667 19.2276 6.3125 15.0326 6.3125C13.0159 6.3125 11.6626 7.41917 11.1101 8.46833H11.0517V6.6475H7.07422V20H11.2159V13.3883C11.2159 11.6475 11.5459 9.96417 13.7017 9.96417C15.8259 9.96417 15.8576 11.9508 15.8576 13.5V20.0008H19.9951Z\"><\/path>\n                  <path d=\"M0.328125 6.64844H4.47479V20.0009H0.328125V6.64844Z\"><\/path>\n                  <path d=\"M2.40167 0C1.07583 0 0 1.07583 0 2.40167C0 3.7275 1.07583 4.82583 2.40167 4.82583C3.7275 4.82583 4.80333 3.7275 4.80333 2.40167C4.8025 1.07583 3.72667 0 2.40167 0V0Z\"><\/path>\n                <\/g>\n              <\/svg><\/div>\n          <\/a>\n        <\/div>\n        <div class=\"w-embed\">\n          <a href=\"https:\/\/twitter.com\/intent\/tweet?text=https:\/\/bgaming.com\/es\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming\" class=\"icon_wrap-social sub\">\n            <div class=\"icon-1x1-small w-embed\">\n              <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"icon-black\" width=\"1.25rem\" max-width=\"20px\" max-height=\"20px\" height=\"1.25rem\" viewBox=\"0 0 1226.37 1226.37\" fill=\"#17161C\">\n                <path d=\"m727.348 519.284 446.727-519.284h-105.86l-387.893 450.887-309.809-450.887h-357.328l468.492 681.821-468.492 544.549h105.866l409.625-476.152 327.181 476.152h357.328l-485.863-707.086zm-144.998 168.544-47.468-67.894-377.686-540.24h162.604l304.797 435.991 47.468 67.894 396.2 566.721h-162.604l-323.311-462.446z\"><\/path>\n              <\/svg>\n            <\/div>\n          <\/a>\n        <\/div>\n        <div class=\"w-embed\">\n          <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/bgaming.com\/es\/news\/crack-the-mystery-of-lost-eggs-in-easter-heist-with-bgaming\" class=\"icon_wrap-social sub\">\n            <div class=\"icon-1x1-small w-embed\"><svg class=\"icon-black\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1.25rem\" height=\"1.25rem\" viewBox=\"0 0 20 20\" fill=\"#17161C\">\n                <path d=\"M13.3312 3.32083H15.1571V0.140833C14.8421 0.0975 13.7587 0 12.4971 0C9.86458 0 8.06125 1.65583 8.06125 4.69917V7.5H5.15625V11.055H8.06125V20H11.6229V11.0558H14.4104L14.8529 7.50083H11.6221V5.05167C11.6229 4.02417 11.8996 3.32083 13.3312 3.32083V3.32083Z\"><\/path>\n              <\/svg><\/div>\n          <\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n\n\n<div class=\"also-like-articles container align wp-block-acf-also-like-articles has-background is-layout-flow wp-block-acf-also-like-articles-is-layout-flow\" id=\"acf-block-680c7fcb46f11\">\n\n  <div class=\"acf-innerblocks-container also-like-articles-wrapper\">\n\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"text-transform:uppercase\">tambi\u00e9n te puede gustar<\/h2>\n\n<\/div>\n\n  <div class=\"also-like-articles__cards\">\n                  <div class=\"also-like-articles__card\">\n          <div class=\"also-like-articles__card--container\">\n                          <img decoding=\"async\" width=\"880\" height=\"730\" src=\"https:\/\/bgaming.com\/wp-content\/uploads\/2025\/05\/66cee7d90d2d4cae8fede694_Train_to_Rio-Grande_880x730.webp\" class=\"game-image wp-post-image\" alt=\"\" loading=\"lazy\" \/>            \n            <div class=\"card-right\">\n                              <div class=\"card-types\">\n                                      <div class=\"label is-white\">\n                      <div>Lanzamiento del Juego<\/div>\n                    <\/div>\n                                  <\/div>\n              \n\n              <div class=\"also-like-articles__card--header\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"arrow-header\" width=\"16\" height=\"16\"\n                  viewBox=\"0 0 16 16\" fill=\"none\">\n                  <g clip-path=\"url(#clip0_1174_8149)\">\n                    <path d=\"M15.8167 7.55759C15.8165 7.5574 15.8163 7.55719 15.8161 7.557L12.5504 4.307C12.3057 4.06353 11.91 4.06444 11.6665 4.30912C11.423 4.55378 11.4239 4.9495 11.6686 5.193L13.8612 7.375H0.625C0.279813 7.375 0 7.65481 0 8C0 8.34519 0.279813 8.625 0.625 8.625H13.8612L11.6686 10.807C11.4239 11.0505 11.423 11.4462 11.6665 11.6909C11.91 11.9356 12.3058 11.9364 12.5504 11.693L15.8162 8.443C15.8163 8.44281 15.8165 8.44259 15.8167 8.4424C16.0615 8.19809 16.0607 7.80109 15.8167 7.55759Z\"\n                      fill=\"#17161C\" \/>\n                  <\/g>\n                  <defs>\n                    <clipPath id=\"clip0_1174_8149\">\n                      <rect width=\"16\" height=\"16\" fill=\"white\" \/>\n                    <\/clipPath>\n                  <\/defs>\n                <\/svg>\n                <div class=\"news-catalog-date\">agosto 28, 2024<\/div>\n                  <div class=\"h3\">\n                      BGAMING PRESENTA UNA NUEVA Y EMOCIONANTE AVENTURA EN EL SALVAJE OESTE CON TREN A R\u00cdO GRANDE                  <\/div>\n              <\/div>\n            <\/div>\n\n            <a href=\"https:\/\/bgaming.com\/es\/news\/bgaming-unveils-thrilling-new-wild-west-adventure-with-train-to-rio-grande\" class=\"game-sets-link\"><\/a>\n          <\/div>\n        <\/div>\n              <div class=\"also-like-articles__card\">\n          <div class=\"also-like-articles__card--container\">\n                          <img decoding=\"async\" width=\"742\" height=\"574\" src=\"https:\/\/bgaming.com\/wp-content\/uploads\/2025\/05\/663b56c5f99f38602f561291_Luck__Magic_Scratch_742x574.webp\" class=\"game-image wp-post-image\" alt=\"\" loading=\"lazy\" \/>            \n            <div class=\"card-right\">\n                              <div class=\"card-types\">\n                                      <div class=\"label is-white\">\n                      <div>Lanzamiento del Juego<\/div>\n                    <\/div>\n                                  <\/div>\n              \n\n              <div class=\"also-like-articles__card--header\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"arrow-header\" width=\"16\" height=\"16\"\n                  viewBox=\"0 0 16 16\" fill=\"none\">\n                  <g clip-path=\"url(#clip0_1174_8149)\">\n                    <path d=\"M15.8167 7.55759C15.8165 7.5574 15.8163 7.55719 15.8161 7.557L12.5504 4.307C12.3057 4.06353 11.91 4.06444 11.6665 4.30912C11.423 4.55378 11.4239 4.9495 11.6686 5.193L13.8612 7.375H0.625C0.279813 7.375 0 7.65481 0 8C0 8.34519 0.279813 8.625 0.625 8.625H13.8612L11.6686 10.807C11.4239 11.0505 11.423 11.4462 11.6665 11.6909C11.91 11.9356 12.3058 11.9364 12.5504 11.693L15.8162 8.443C15.8163 8.44281 15.8165 8.44259 15.8167 8.4424C16.0615 8.19809 16.0607 7.80109 15.8167 7.55759Z\"\n                      fill=\"#17161C\" \/>\n                  <\/g>\n                  <defs>\n                    <clipPath id=\"clip0_1174_8149\">\n                      <rect width=\"16\" height=\"16\" fill=\"white\" \/>\n                    <\/clipPath>\n                  <\/defs>\n                <\/svg>\n                <div class=\"news-catalog-date\">mayo 8, 2024<\/div>\n                  <div class=\"h3\">\n                      Los h\u00e9roes populares de BGaming regresan en Luck &#038; Magic Scratch                  <\/div>\n              <\/div>\n            <\/div>\n\n            <a href=\"https:\/\/bgaming.com\/es\/news\/bgamings-popular-heroes-return-in-luck-magic-scratch\" class=\"game-sets-link\"><\/a>\n          <\/div>\n        <\/div>\n              <div class=\"also-like-articles__card\">\n          <div class=\"also-like-articles__card--container\">\n                          <img decoding=\"async\" width=\"880\" height=\"730\" src=\"https:\/\/bgaming.com\/wp-content\/uploads\/2026\/06\/Money_Maker_880x730.png\" class=\"game-image wp-post-image\" alt=\"\" loading=\"lazy\" \/>            \n            <div class=\"card-right\">\n                              <div class=\"card-types\">\n                                      <div class=\"label is-white\">\n                      <div>Lanzamiento del Juego<\/div>\n                    <\/div>\n                                  <\/div>\n              \n\n              <div class=\"also-like-articles__card--header\">\n                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"arrow-header\" width=\"16\" height=\"16\"\n                  viewBox=\"0 0 16 16\" fill=\"none\">\n                  <g clip-path=\"url(#clip0_1174_8149)\">\n                    <path d=\"M15.8167 7.55759C15.8165 7.5574 15.8163 7.55719 15.8161 7.557L12.5504 4.307C12.3057 4.06353 11.91 4.06444 11.6665 4.30912C11.423 4.55378 11.4239 4.9495 11.6686 5.193L13.8612 7.375H0.625C0.279813 7.375 0 7.65481 0 8C0 8.34519 0.279813 8.625 0.625 8.625H13.8612L11.6686 10.807C11.4239 11.0505 11.423 11.4462 11.6665 11.6909C11.91 11.9356 12.3058 11.9364 12.5504 11.693L15.8162 8.443C15.8163 8.44281 15.8165 8.44259 15.8167 8.4424C16.0615 8.19809 16.0607 7.80109 15.8167 7.55759Z\"\n                      fill=\"#17161C\" \/>\n                  <\/g>\n                  <defs>\n                    <clipPath id=\"clip0_1174_8149\">\n                      <rect width=\"16\" height=\"16\" fill=\"white\" \/>\n                    <\/clipPath>\n                  <\/defs>\n                <\/svg>\n                <div class=\"news-catalog-date\">junio 10, 2026<\/div>\n                  <div class=\"h3\">\n                      ALINEA LOS BILLETES EN MONEY MAKER DE BGAMING                  <\/div>\n              <\/div>\n            <\/div>\n\n            <a href=\"https:\/\/bgaming.com\/es\/news\/alinea-los-billetes-en-la-maquina-de-hacer-dinero-de-bgaming\" class=\"game-sets-link\"><\/a>\n          <\/div>\n        <\/div>\n                    <a href=\"\/es\/news\" class=\"card_button article w-inline-block\">\n                                  <div class=\"button is-text\">\n              <div>Todas las Noticias<\/div>\n            <\/div>\n                    <div class=\"icon_button-text w-embed\"><svg class=\"icon-black\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"1.25rem\" height=\"1.25rem\" viewBox=\"0 0 20 20\" fill=\"#17161C\">\n              <path d=\"M19.7709 9.44699C19.7706 9.44676 19.7704 9.44648 19.7702 9.44625L15.688 5.38375C15.3821 5.07941 14.8875 5.08054 14.5831 5.3864C14.2787 5.69222 14.2799 6.18687 14.5857 6.49125L17.3265 9.21875H0.78125C0.349766 9.21875 0 9.56851 0 10C0 10.4315 0.349766 10.7812 0.78125 10.7812H17.3264L14.5857 13.5087C14.2799 13.8131 14.2788 14.3078 14.5831 14.6136C14.8875 14.9195 15.3822 14.9205 15.688 14.6162L19.7702 10.5537C19.7704 10.5535 19.7706 10.5532 19.7709 10.553C20.0769 10.2476 20.0759 9.75137 19.7709 9.44699Z\"><\/path>\n            <\/svg><\/div>\n        <\/a>\n            <\/div>\n<\/div>\n\n\n","protected":false},"featured_media":12171,"template":"","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":""},"news_type":[3039],"class_list":["post-14153","news","type-news","status-publish","has-post-thumbnail","hentry","news_type-game-release"],"acf":[],"_links":{"self":[{"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/news\/14153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/media\/12171"}],"wp:attachment":[{"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/media?parent=14153"}],"wp:term":[{"taxonomy":"news_type","embeddable":true,"href":"https:\/\/bgaming.com\/es\/wp-json\/wp\/v2\/news_type?post=14153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}